{"id":2017,"date":"2024-01-09T10:17:41","date_gmt":"2024-01-09T09:17:41","guid":{"rendered":"https:\/\/ittester.sk\/sin-categorizar\/configuracion-elementos-medidor\/"},"modified":"2024-06-25T16:01:52","modified_gmt":"2024-06-25T14:01:52","slug":"configuracion-elementos-medidor","status":"publish","type":"post","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/","title":{"rendered":"Elementos de configuraci\u00f3n de JMeter"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00cdndice<\/h2>\n<div class=\"wp-block-aioseo-table-of-contents\"><ul><li><a class=\"aioseo-toc-item\" href=\"#aioseo-co-su-konfiguracne-prvky-v-jmeter\">\u010co s\u00fa konfigura\u010dn\u00e9 prvky v JMeter?<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-prvky-konfiguracie-poskytovane-v-jmeter\">Prvky konfigur\u00e1cie poskytovan\u00e9 v JMeter<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-csv-data-set-config\">CSV Data Set Config<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-http-cache-manager\">HTTP Cache Manager<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-http-cookie-manager\">HTTP Cookie Manager<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-premenne-definovane-pouzivatelom\">Premenn\u00e9 definovan\u00e9 pou\u017e\u00edvate\u013eom<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-nahodna-premenna\">N\u00e1hodn\u00e1 premenn\u00e1<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-pocitadlo-counter\">Po\u010d\u00edtadlo (counter)<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-konfiguracia-pripojenia-jdbc\">Konfigur\u00e1cia pripojenia JDBC<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-predvolene-nastavenia-poziadavky-ftp\">Predvolen\u00e9 nastavenia po\u017eiadavky FTP<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-dns-cache-manager\">DNS Cache Manager<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-spravca-autorizacie-http\">Spr\u00e1vca autoriz\u00e1cie HTTP<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-predvolene-nastavenia-http-requests\">Predvolen\u00e9 nastavenia HTTP requests<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-http-header-manager\">HTTP Header Manager<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-predvolene-hodnoty-poziadaviek-java\">Predvolen\u00e9 hodnoty po\u017eiadaviek Java<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-keystore-configuration\">Keystore Configuration<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-login-config-element\">Login Config Element<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-ldap-request-defaults\">LDAP Request Defaults<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-ldap-extended-request-defaults\">LDAP Extended Request Defaults<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-konfiguracia-samplera-tcp\">Konfigur\u00e1cia samplera TCP<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-jednoduchy-konfiguracny-prvok\">Jednoduch\u00fd konfigura\u010dn\u00fd prvok<\/a><\/li><\/ul><\/div>\n<h2 class=\"wp-block-heading\" id=\"aioseo-co-su-konfiguracne-prvky-v-jmeter\">\u00bfQu\u00e9 son los elementos de configuraci\u00f3n en JMeter?<\/h2>\n\n<p>Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor. Estos elementos se a\u00f1aden al mismo nivel o superior de los muestreadores que queremos configurar.  <strong>C\u00f3mo a\u00f1adir elementos de configuraci\u00f3n-<\/strong><\/p>\n\n<p><strong>&gt;&gt;&gt; Haz clic con el bot\u00f3n derecho en cualquiera de los Planes de Prueba\/Grupo de Hilos\/Controlador L\u00f3gico &#8211; ve a A\u00f1adir &#8211; ve a Elemento de Configuraci\u00f3n &#8211; haz clic en el elemento de configuraci\u00f3n deseado<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"640\" src=\"https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/2024-01-04_10h14_21.jpg\" alt=\"\" class=\"wp-image-780\" srcset=\"https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/2024-01-04_10h14_21.jpg 990w, https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/2024-01-04_10h14_21-300x194.jpg 300w, https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/2024-01-04_10h14_21-768x496.jpg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\" id=\"aioseo-prvky-konfiguracie-poskytovane-v-jmeter\">Elementos de configuraci\u00f3n proporcionados en JMeter<\/h2>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-csv-data-set-config\">Configuraci\u00f3n del conjunto de datos CSV<\/h2>\n\n<p>CSV Data Set Config se utiliza para leer datos de un archivo CSV, insertar los datos en una variable y, a continuaci\u00f3n, utilizar la(s) variable(s) en las solicitudes del muestreador.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-http-cache-manager\">Gestor de cach\u00e9 HTTP<\/h2>\n\n<p>HTTP Cache Manager se utiliza en los scripts de prueba para a\u00f1adir funciones de cach\u00e9 a las aplicaciones web. Este elemento s\u00f3lo debe a\u00f1adirse al mismo nivel o superior que el requisito de muestreo en el que se requiere el almacenamiento en cach\u00e9 de caracter\u00edsticas.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-http-cookie-manager\">Gestor de Cookies HTTP<\/h2>\n\n<p>El Gestor de Cookies HTTP es necesario para procesar las sesiones proporcionando la funcionalidad de almacenar y enviar cookies.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-premenne-definovane-pouzivatelom\">Variables definidas por el usuario<\/h2>\n\n<p>Como su nombre indica, el elemento de configuraci\u00f3n Variable definida por el usuario se utiliza para crear las variables de valor (pares clave-valor) que se utilizan en todo el script de prueba.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-nahodna-premenna\">Variable aleatoria<\/h2>\n\n<p>El elemento de configuraci\u00f3n variable aleatoria se utiliza para generar valores num\u00e9ricos aleatorios dentro de un rango de valores m\u00ednimo y m\u00e1ximo especificados.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-pocitadlo-counter\">Contador<\/h2>\n\n<p>El elemento de configuraci\u00f3n Contador se utiliza para crear una variable que se incrementa en cada iteraci\u00f3n en un valor especificado en el rango de valores m\u00ednimo y m\u00e1ximo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-konfiguracia-pripojenia-jdbc\">Configuraci\u00f3n de la conexi\u00f3n JDBC<\/h2>\n\n<p>La Configuraci\u00f3n de la Conexi\u00f3n JDBC se utiliza con el Muestreador de Peticiones JDBC para crear configuraciones de conexi\u00f3n JDBC.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-predvolene-nastavenia-poziadavky-ftp\">Configuraci\u00f3n por defecto de la solicitud FTP<\/h2>\n\n<p>Las peticiones FTP por defecto se utilizan para crear configuraciones por defecto al probar servidores FTP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-dns-cache-manager\">Administrador de cach\u00e9 DNS<\/h2>\n\n<p>DNS Cache Manager se utiliza cuando se prueban aplicaciones para los equilibradores de carga.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-spravca-autorizacie-http\">Gestor de autorizaci\u00f3n HTTP<\/h2>\n\n<p>El Gestor de Autorizaciones HTTP se utiliza cuando se prueban aplicaciones que requieren varios inicios de sesi\u00f3n para proporcionar autorizaci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-predvolene-nastavenia-http-requests\">Configuraci\u00f3n por defecto de las peticiones HTTP<\/h2>\n\n<p>El elemento de configuraci\u00f3n Valores por defecto de las peticiones HTTP se utiliza para establecer los valores por defecto de las peticiones HTTP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-http-header-manager\">Gestor de cabeceras HTTP<\/h2>\n\n<p>El Gestor de Cabeceras HTTP se utiliza para reescribir las cabeceras de las peticiones HTTP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-predvolene-hodnoty-poziadaviek-java\">Valores por defecto de la petici\u00f3n Java<\/h2>\n\n<p>Los elementos de configuraci\u00f3n Valores por defecto de las peticiones Java se utilizan para especificar valores por defecto para el Muestreador de peticiones Java.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-keystore-configuration\">Configuraci\u00f3n del almac\u00e9n de claves<\/h2>\n\n<p>El elemento Configuraci\u00f3n del almac\u00e9n de claves se utiliza para configurar la carga del almac\u00e9n de claves.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-login-config-element\">Elemento de configuraci\u00f3n de inicio de sesi\u00f3n<\/h2>\n\n<p>El elemento de configuraci\u00f3n de inicio de sesi\u00f3n se utiliza para crear credenciales de inicio de sesi\u00f3n predeterminadas para los muestreadores que utilizan el nombre de usuario y la contrase\u00f1a de su configuraci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-ldap-request-defaults\">Petici\u00f3n LDAP por defecto<\/h2>\n\n<p>Los valores predeterminados de solicitud LDAP se utilizan para crear configuraciones predeterminadas al probar servidores LDAP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-ldap-extended-request-defaults\">Valores por defecto de la petici\u00f3n extendida LDAP<\/h2>\n\n<p>Los valores por defecto de petici\u00f3n extendida LDAP se utilizan para crear configuraciones por defecto para los muestreadores de petici\u00f3n extendida LDAP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-konfiguracia-samplera-tcp\">Configuraci\u00f3n del muestreador TCP<\/h2>\n\n<p>La configuraci\u00f3n del muestreador TCP se utiliza para crear ajustes por defecto para el muestreador TCP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-jednoduchy-konfiguracny-prvok\">Elemento de configuraci\u00f3n simple<\/h2>\n\n<p>El elemento Simple Config se utiliza para crear pares clave-valor que pueden utilizarse en todo el script de prueba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.<\/p>\n","protected":false},"author":8,"featured_media":2019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutorial-de-jmeter"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Zoltan\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT tester - Z\u00e1kladn\u00e9 inform\u00e1cie o testovan\u00ed softv\u00e9ru\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Elementos de configuraci\u00f3n de JMeter - IT tester\" \/>\n\t\t<meta property=\"og:description\" content=\"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-01-09T09:17:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-25T14:01:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Elementos de configuraci\u00f3n de JMeter - IT tester\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.\" \/>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"nizijct9c2\");\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Elementos de configuraci\u00f3n de JMeter - IT tester<\/title>\n\n","aioseo_head_json":{"title":"Elementos de configuraci\u00f3n de JMeter - IT tester","description":"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.","canonical_url":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"IT tester - Z\u00e1kladn\u00e9 inform\u00e1cie o testovan\u00ed softv\u00e9ru","og:type":"article","og:title":"Elementos de configuraci\u00f3n de JMeter - IT tester","og:description":"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.","og:url":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/","article:published_time":"2024-01-09T09:17:41+00:00","article:modified_time":"2024-06-25T14:01:52+00:00","twitter:card":"summary_large_image","twitter:title":"Elementos de configuraci\u00f3n de JMeter - IT tester","twitter:description":"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor."},"aioseo_meta_data":{"post_id":"2017","title":null,"description":"Los elementos config de JMeter se utilizan para configurar o modificar las peticiones de muestreo enviadas al servidor.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"none","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-18 08:13:41","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-06-25 14:01:52","updated":"2026-05-18 08:13:41"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/\" title=\"Pruebas de rendimiento\">Pruebas de rendimiento<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/\" title=\"Tutorial de Jmeter\">Tutorial de Jmeter<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tElementos de configuraci\u00f3n de JMeter\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ittester.sk\/es\/"},{"label":"Pruebas de rendimiento","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/"},{"label":"Tutorial de Jmeter","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/"},{"label":"Elementos de configuraci\u00f3n de JMeter","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/configuracion-elementos-medidor\/"}],"_links":{"self":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/2017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/comments?post=2017"}],"version-history":[{"count":1,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/2017\/revisions"}],"predecessor-version":[{"id":2020,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/2017\/revisions\/2020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media\/2019"}],"wp:attachment":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media?parent=2017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/categories?post=2017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/tags?post=2017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}