{"id":1985,"date":"2024-01-11T10:24:28","date_gmt":"2024-01-11T09:24:28","guid":{"rendered":"https:\/\/ittester.sk\/sin-categorizar\/postprocesadores-jmeter\/"},"modified":"2024-06-25T16:01:42","modified_gmt":"2024-06-25T14:01:42","slug":"postprocesadores-jmeter","status":"publish","type":"post","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/","title":{"rendered":"Postprocesadores JMeter"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00cdndice<\/h2>\n<div class=\"wp-block-aioseo-table-of-contents\"><ul><li><a class=\"aioseo-toc-item\" href=\"#aioseo-co-su-postprocesory-v-jmeter\">\u010co s\u00fa postprocesory v JMeter?<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-rozne-typy-postprocesorov-v-jmeter\">R\u00f4zne typy postprocesorov v\u00a0JMeter<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-extraktor-regulernych-vyrazov\">Extraktor regul\u00e9rnych v\u00fdrazov<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-beanshell-postprocesor\">BeanShell postprocesor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-extraktor-css-jquery\">Extraktor CSS\/JQuery<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-xpath-extractor\">XPath Extractor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-debug-postprocessor\">Debug PostProcessor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-jsr223-postprocessor\">JSR223 PostProcessor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-jdbc-postprocessor\">JDBC PostProcessor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-json-path-postprocessor\">JSON Path PostProcessor<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-result-status-action-handler\">Result Status Action Handler<\/a><\/li><\/ul><\/div>\n<h2 class=\"wp-block-heading\" id=\"aioseo-co-su-postprocesory-v-jmeter\">\u00bfQu\u00e9 son los postprocesadores en JMeter?<\/h2>\n\n<p>Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud. Estos postprocesadores suelen utilizarse para extraer determinados valores de la respuesta de una solicitud de muestreo, por ejemplo podemos extraer el valor de la variable de sesi\u00f3n de la petici\u00f3n HTTP y pasar el valor de la variable de sesi\u00f3n a las siguientes peticiones.  <strong>C\u00f3mo a\u00f1adir un postprocesador en JMeter-<\/strong><\/p>\n\n<p><strong>&gt;&gt;&gt; Haz clic con el bot\u00f3n derecho en Grupo de hilos\/Controlador l\u00f3gico &#8211; ve a A\u00f1adir &#8211; ve a \u00abPostprocesadores\u00bb &#8211; haz clic en el elemento postprocesador deseado<\/strong><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/postprocesory-screenshot-1000-500.webp\" alt=\"\" class=\"wp-image-825\" srcset=\"https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/postprocesory-screenshot-1000-500.webp 1000w, https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/postprocesory-screenshot-1000-500-300x150.webp 300w, https:\/\/ittester.sk\/wp-content\/uploads\/2024\/01\/postprocesory-screenshot-1000-500-768x384.webp 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\" id=\"aioseo-rozne-typy-postprocesorov-v-jmeter\">Diferentes tipos de postprocesadores en JMeter<\/h2>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-extraktor-regulernych-vyrazov\">Extractor de expresiones regulares<\/h2>\n\n<p>El Extractor de Expresiones Regulares es el postprocesador m\u00e1s utilizado. Se utiliza para extraer valores de la respuesta HTTP utilizando una expresi\u00f3n regular y para almacenar los valores en una variable. Despu\u00e9s, esta variable se puede utilizar como par\u00e1metro de solicitud para otros muestreadores, o se puede utilizar para otros fines, como aserciones, depuraci\u00f3n, guardar en un archivo, etc.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-beanshell-postprocesor\">Postprocesador BeanShell<\/h2>\n\n<p>El postprocesador BeanShell se utiliza para realizar alguna operaci\u00f3n utilizando el script BeanShell despu\u00e9s de procesar una petici\u00f3n del muestreador.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-extraktor-css-jquery\">Extractor CSS\/JQuery<\/h2>\n\n<p>El Extractor CSS\/JQuery se utiliza para extraer valores de una respuesta HTTP utilizando expresiones CSS o jQuery y luego almacenar el valor extra\u00eddo en una variable.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-xpath-extractor\">Extractor XPath<\/h2>\n\n<p>El Extractor XPath se utiliza para extraer valores de una respuesta HTTP utilizando expresiones CSS o jQuery, y luego almacenar el valor extra\u00eddo en una variable.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-debug-postprocessor\">Depurar PostProcesador<\/h2>\n\n<p>El PostProcesador de depuraci\u00f3n se utiliza para crear una submuestra que tenga propiedades de solicitudes de muestreo anteriores, propiedades de JMeter, variables de JMeter o propiedades del sistema.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-jsr223-postprocessor\">PostProcesador JSR223<\/h2>\n\n<p>El PostProcesador JSR223 se utiliza para realizar una operaci\u00f3n espec\u00edfica utilizando secuencias de comandos JSR223 despu\u00e9s de procesar una solicitud de muestreo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-jdbc-postprocessor\">PostProcesador JDBC<\/h2>\n\n<p>El PostProcesador JDBC se utiliza para ejecutar determinadas consultas SQL especificadas despu\u00e9s de que el muestreador haya procesado la petici\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-json-path-postprocessor\">PostProcesador de rutas JSON<\/h2>\n\n<p>El PostProcesador JSON Path se utiliza para extraer datos de una respuesta JSON utilizando la sintaxis JSON-Path.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-result-status-action-handler\">Resultado Estado Acci\u00f3n Gestor<\/h2>\n\n<p>El manejador de acciones de estado de resultados se utiliza para detener un grupo de hilos o una prueba entera si falla un muestreador concreto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.<\/p>\n","protected":false},"author":8,"featured_media":1987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutorial-de-jmeter"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Zoltan\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT tester - Z\u00e1kladn\u00e9 inform\u00e1cie o testovan\u00ed softv\u00e9ru\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Postprocesadores JMeter - IT tester\" \/>\n\t\t<meta property=\"og:description\" content=\"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-01-11T09:24:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-25T14:01:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Postprocesadores JMeter - IT tester\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.\" \/>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"nizijct9c2\");\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Postprocesadores JMeter - IT tester<\/title>\n\n","aioseo_head_json":{"title":"Postprocesadores JMeter - IT tester","description":"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.","canonical_url":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"IT tester - Z\u00e1kladn\u00e9 inform\u00e1cie o testovan\u00ed softv\u00e9ru","og:type":"article","og:title":"Postprocesadores JMeter - IT tester","og:description":"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.","og:url":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/","article:published_time":"2024-01-11T09:24:28+00:00","article:modified_time":"2024-06-25T14:01:42+00:00","twitter:card":"summary_large_image","twitter:title":"Postprocesadores JMeter - IT tester","twitter:description":"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud."},"aioseo_meta_data":{"post_id":"1985","title":null,"description":"Los postprocesadores son elementos del plan de pruebas que se utilizan para realizar determinadas acciones despu\u00e9s de que el muestreador haya procesado una solicitud.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"none","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-18 08:17:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-06-25 14:01:41","updated":"2026-05-18 08:17:07"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/\" title=\"Pruebas de rendimiento\">Pruebas de rendimiento<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/\" title=\"Tutorial de Jmeter\">Tutorial de Jmeter<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPostprocesadores JMeter\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ittester.sk\/es\/"},{"label":"Pruebas de rendimiento","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/"},{"label":"Tutorial de Jmeter","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/"},{"label":"Postprocesadores JMeter","link":"https:\/\/ittester.sk\/es\/pruebas-de-rendimiento\/tutorial-de-jmeter\/postprocesadores-jmeter\/"}],"_links":{"self":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/comments?post=1985"}],"version-history":[{"count":1,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1985\/revisions"}],"predecessor-version":[{"id":1989,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1985\/revisions\/1989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media\/1987"}],"wp:attachment":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media?parent=1985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/categories?post=1985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/tags?post=1985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}