{"id":1879,"date":"2024-03-07T11:12:07","date_gmt":"2024-03-07T10:12:07","guid":{"rendered":"https:\/\/ittester.sk\/sin-categorizar\/testng-tutorial\/"},"modified":"2024-07-11T09:43:06","modified_gmt":"2024-07-11T07:43:06","slug":"testng-tutorial","status":"publish","type":"post","link":"https:\/\/ittester.sk\/es\/sin-categorizar\/tutorial-testng\/testng-tutorial\/","title":{"rendered":"Tutorial TestNG"},"content":{"rendered":"\n<p>TestNG es uno de los marcos de pruebas de c\u00f3digo abierto m\u00e1s utilizados. En este tutorial, aprenderemos varias caracter\u00edsticas de TestNG: implementaci\u00f3n de pruebas basadas en datos, soporte de parametrizaci\u00f3n, varias anotaciones \u00fatiles y agrupaci\u00f3n de casos de prueba que ayudan a crear marcos de pruebas robustos y potentes.<\/p>\n\n<h2 class=\"wp-block-heading\">Tutorial TestNG con Selenium<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Introducci\u00f3n a TestNG<\/li>\n\n\n\n<li>Script de ejemplo de Selenium Webdriver con TestNG<\/li>\n\n\n\n<li>Anotaciones TestNG<\/li>\n\n\n\n<li>Pruebas basadas en datos en TestNG<\/li>\n\n\n\n<li>Reejecutar una prueba fallida en TestNG<\/li>\n\n\n\n<li>Ejecutar pruebas Selenium en paralelo utilizando TestNG<\/li>\n\n\n\n<li>Probar varios navegadores en Selenium utilizando TestNG<\/li>\n\n\n\n<li>Configuraci\u00f3n de la prioridad de las pruebas en TestNG<\/li>\n\n\n\n<li>Dependencia en las pruebas<\/li>\n\n\n\n<li>Aserci\u00f3n suave en TestNG<\/li>\n\n\n\n<li>L\u00edmites de tiempo en TestNG<\/li>\n\n\n\n<li>Preguntas de la entrevista TestNG<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Preguntas de la entrevista para TestNG<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Preguntas de la entrevista para TestNG<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tutoriales gratuitos de TestNG para principiantes. Aprende TestNG con Selenium WebDriver en Java con ejemplos y scripts de muestra.<\/p>\n","protected":false},"author":8,"featured_media":1880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-1879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutorial-testng"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/comments?post=1879"}],"version-history":[{"count":1,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1879\/revisions"}],"predecessor-version":[{"id":1882,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/posts\/1879\/revisions\/1882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media\/1880"}],"wp:attachment":[{"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/media?parent=1879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/categories?post=1879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ittester.sk\/es\/wp-json\/wp\/v2\/tags?post=1879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}