{"id":359,"date":"2023-07-28T15:33:29","date_gmt":"2023-07-28T13:33:29","guid":{"rendered":"https:\/\/ittester.sk\/unkategorisiert\/ebenen-der-softwarepruefung\/"},"modified":"2024-06-05T09:34:37","modified_gmt":"2024-06-05T07:34:37","slug":"software-testing-levels","status":"publish","type":"post","link":"https:\/\/ittester.sk\/de\/manuelles-testen\/software-testing-levels\/","title":{"rendered":"Ebenen der Softwarepr\u00fcfung"},"content":{"rendered":"\n<p>Softwaretests k\u00f6nnen auf verschiedenen Ebenen des Softwareentwicklungsprozesses durchgef\u00fchrt werden. Die Durchf\u00fchrung von Testaktivit\u00e4ten auf mehreren Ebenen hilft, Fehler fr\u00fchzeitig zu erkennen und die Qualit\u00e4t des Softwareprodukts zu verbessern. In diesem Text werden wir verschiedene Ebenen des Testens besprechen, n\u00e4mlich Einheitstests, Integrationstests, Systemtests und Abnahmetests.<\/p>\n\n<p>In diesem Abschnitt werden die einzelnen Teststufen kurz beschrieben, und in den folgenden Abschnitten wird jede einzelne Stufe anhand eines Beispiels und einer ausf\u00fchrlichen Erkl\u00e4rung erl\u00e4utert.<\/p>\n\n<h2 class=\"wp-block-heading\">Inhalts\u00fcbersicht<\/h2>\n<div class=\"wp-block-aioseo-table-of-contents\"><ul><li><a class=\"aioseo-toc-item\" href=\"#aioseo-unit-testovanie-unit-testing\">Unit testovanie (unit testing)<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-integracne-testovanie-integration-testing\">Integra\u010dn\u00e9 testovanie (integration testing)<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-testovanie-systemu-system-testing\">Testovanie syst\u00e9mu (system testing)<\/a><\/li><li><a class=\"aioseo-toc-item\" href=\"#aioseo-akceptacne-testovanie-acceptance-testing\">Akcepta\u010dn\u00e9 testovanie (acceptance testing)<\/a><\/li><\/ul><\/div>\n<h2 class=\"wp-block-heading\" id=\"aioseo-unit-testovanie-unit-testing\">Einheitliche Pr\u00fcfung<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Unit-Tests sind die erste Teststufe, die in der Regel von Entwicklern durchgef\u00fchrt wird.<\/li>\n\n\n\n<li>Beim Testen wird das Modul oder die Komponente isoliert getestet.<\/li>\n\n\n\n<li>Da sich die Pr\u00fcfung auf ein bestimmtes Modul oder eine bestimmte Komponente beschr\u00e4nkt, ist eine ersch\u00f6pfende Pr\u00fcfung m\u00f6glich.<\/li>\n\n\n\n<li>Vorteil &#8211; der Fehler kann fr\u00fchzeitig erkannt werden, was Zeit und Geld bei der Beseitigung spart.<\/li>\n\n\n\n<li>Einschr\u00e4nkung &#8211; Integrationsprobleme werden in diesem Stadium nicht erkannt, Module k\u00f6nnen isoliert perfekt funktionieren, aber Probleme bei der Verbindung zwischen den Modulen haben.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-integracne-testovanie-integration-testing\">Integrationstests<\/h2>\n\n<p>Integrationstests sind die zweite Testebene, auf der wir eine Gruppe von zusammenh\u00e4ngenden Modulen testen.<\/p>\n\n<p>Sie zielt darauf ab, Probleme mit der Verbindung zwischen den Modulen zu finden, d. h. j. ob die einzelnen Einheiten ordnungsgem\u00e4\u00df in das Teilsystem integriert werden k\u00f6nnen. Es gibt vier Arten: Big-Bang-, Top-Down-, Bottom-Up- und Hybrid-Tests.<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Bei der Integration mit <strong>Big-Bang-Tests<\/strong> werden alle Module zuerst ben\u00f6tigt und dann integriert. Nach der Integration erfolgt die Pr\u00fcfung der integrierten Einheit als Ganzes.<\/li>\n\n\n\n<li>Bei <strong>Top-Down-Integrationstests <\/strong> beginnt der Testablauf mit den in der Hierarchie h\u00f6her stehenden Top-Level-Modulen und endet mit den darunter liegenden Modulen, da die M\u00f6glichkeit besteht, dass die darunter liegenden Module nicht entwickelt werden. Daher werden in solchen F\u00e4llen Plugins (Stubs) verwendet, die nichts anderes als Dummy-Module oder -Funktionen sind, die den Betrieb des Moduls simulieren, indem sie die vom Modul empfangenen Parameter akzeptieren und ein akzeptables Ergebnis liefern.<\/li>\n\n\n\n<li><strong>Bottom-up-Integrationstests <\/strong> basieren ebenfalls auf einem inkrementellen Ansatz, beginnen jedoch mit den Modulen der unteren Ebene und arbeiten sich bis zu den Modulen der h\u00f6heren Ebene vor. Auch hier ist es m\u00f6glich, dass die Module der h\u00f6heren Ebene nicht zu dem Zeitpunkt entwickelt werden, zu dem die Module der unteren Ebene getestet werden. Aus diesem Grund werden in diesen F\u00e4llen Fahrer eingesetzt. Diese Treiber simulieren die Funktionalit\u00e4t von Modulen h\u00f6herer Ebenen, um Module niedrigerer Ebenen zu testen.<\/li>\n\n\n\n<li><strong>Hybride Integrationstests<\/strong> werden auch als Sandwich-Integrationsansatz bezeichnet. Dieser Ansatz ist eine Kombination aus Top-down- und Bottom-up-Integrationstests. In diesem Fall beginnt die Integration in der mittleren Schicht, und die Tests werden in beide Richtungen durchgef\u00fchrt, wobei gegebenenfalls sowohl Stubs als auch Treiber verwendet werden.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-testovanie-systemu-system-testing\">Systempr\u00fcfung<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Die Systempr\u00fcfung ist die dritte Stufe der Pr\u00fcfung.<\/li>\n\n\n\n<li>Dies ist die Testebene, auf der die gesamte integrierte Anwendung als Ganzes getestet wird.<\/li>\n\n\n\n<li>Damit soll festgestellt werden, ob die Anwendung den gesch\u00e4ftlichen Anforderungen entspricht.<\/li>\n\n\n\n<li>Systemtests werden in einer Umgebung durchgef\u00fchrt, die einer Produktionsumgebung sehr \u00e4hnlich ist.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"aioseo-akceptacne-testovanie-acceptance-testing\">Abnahmetests<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Abnahmetests sind die letzte und eine der wichtigsten Teststufen, nach deren erfolgreichem Abschluss die Anwendung f\u00fcr die Produktion freigegeben wird.<\/li>\n\n\n\n<li>Ziel ist es, sicherzustellen, dass das Produkt die festgelegten gesch\u00e4ftlichen Anforderungen innerhalb eines definierten Qualit\u00e4tsstandards erf\u00fcllt.<\/li>\n\n\n\n<li>Es gibt zwei Arten von Akzeptanztests &#8211; Alpha-Tests und Beta-Tests.<\/li>\n\n\n\n<li>Wenn die Abnahmetests von Testern oder anderen internen Mitarbeitern des Unternehmens beim Entwickler durchgef\u00fchrt werden, spricht man von Alpha-Tests.<\/li>\n\n\n\n<li>Benutzerakzeptanztests, die von Endbenutzern am Arbeitsplatz des Endbenutzers durchgef\u00fchrt werden, nennt man Betatests.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Durchf\u00fchrung von Testaktivit\u00e4ten auf mehreren Ebenen hilft, Fehler fr\u00fchzeitig zu erkennen und die Qualit\u00e4t des Softwareprodukts zu verbessern.<\/p>\n","protected":false},"author":8,"featured_media":1390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manuelles-testen"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":5,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":1392,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/posts\/359\/revisions\/1392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ittester.sk\/de\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}